

{"id":346,"date":"2025-10-15T13:21:57","date_gmt":"2025-10-15T11:21:57","guid":{"rendered":"https:\/\/beaware.inria.fr\/?page_id=346"},"modified":"2025-10-15T13:28:54","modified_gmt":"2025-10-15T11:28:54","slug":"tools","status":"publish","type":"page","link":"https:\/\/beaware.inria.fr\/fr\/tools\/","title":{"rendered":"Outils"},"content":{"rendered":"<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><a href=\"https:\/\/beaware.inria.fr\/files\/2025\/10\/Tullibee.png\"><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"200\" src=\"https:\/\/beaware.inria.fr\/files\/2025\/10\/Tullibee.png\" alt=\"\" class=\"wp-image-347\" srcset=\"https:\/\/beaware.inria.fr\/files\/2025\/10\/Tullibee.png 340w, https:\/\/beaware.inria.fr\/files\/2025\/10\/Tullibee-300x176.png 300w, https:\/\/beaware.inria.fr\/files\/2025\/10\/Tullibee-150x88.png 150w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/bivwac.fr\/tools\/tulibee\/\"><a href=\"https:\/\/bivwac.fr\/fr\/tulibee\/\">[2025] Tullibee: Une passerelle Unity-Otree<\/a><\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><a href=\"https:\/\/beaware.inria.fr\/files\/2025\/10\/ARwavs.png\"><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"200\" src=\"https:\/\/beaware.inria.fr\/files\/2025\/10\/ARwavs.png\" alt=\"\" class=\"wp-image-348\" srcset=\"https:\/\/beaware.inria.fr\/files\/2025\/10\/ARwavs.png 340w, https:\/\/beaware.inria.fr\/files\/2025\/10\/ARwavs-300x176.png 300w, https:\/\/beaware.inria.fr\/files\/2025\/10\/ARwavs-150x88.png 150w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/bivwac.fr\/tools\/arwavs\/\"><br>[2024] Documentation de l&rsquo;ARwavs : comment l&rsquo;installer<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[2025] Tullibee: Une passerelle Unity-Otree [2024] Documentation de l&rsquo;ARwavs : comment l&rsquo;installer<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/beaware.inria.fr\/fr\/tools\/\"><span>Continue reading<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":2424,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-346","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/pages\/346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/users\/2424"}],"replies":[{"embeddable":true,"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/comments?post=346"}],"version-history":[{"count":4,"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/pages\/346\/revisions"}],"predecessor-version":[{"id":353,"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/pages\/346\/revisions\/353"}],"wp:attachment":[{"href":"https:\/\/beaware.inria.fr\/fr\/wp-json\/wp\/v2\/media?parent=346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}